{"id":526,"count":1,"description":"","link":"https:\/\/www.boatcoversdirect.com\/boat-lovers\/tag\/protective-boat-cover\/","name":"protective boat cover","slug":"protective-boat-cover","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>protective boat cover Archives - Boat Lovers Direct<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"protective boat cover Archives - Boat Lovers Direct\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.boatcoversdirect.com\/boat-lovers\/tag\/protective-boat-cover\/\" \/>\n<meta property=\"og:site_name\" content=\"Boat Lovers Direct\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.boatcoversdirect.com\/boat-lovers\/tag\/protective-boat-cover\/\",\"url\":\"https:\/\/www.boatcoversdirect.com\/boat-lovers\/tag\/protective-boat-cover\/\",\"name\":\"protective boat cover Archives - Boat Lovers Direct\",\"isPartOf\":{\"@id\":\"https:\/\/www.boatcoversdirect.com\/boat-lovers\/#website\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.boatcoversdirect.com\/boat-lovers\/#website\",\"url\":\"https:\/\/www.boatcoversdirect.com\/boat-lovers\/\",\"name\":\"Boat Lovers Direct\",\"description\":\"The official blog of Boat Covers Direct\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.boatcoversdirect.com\/boat-lovers\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"protective boat cover Archives - Boat Lovers Direct","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"protective boat cover Archives - Boat Lovers Direct","og_url":"https:\/\/www.boatcoversdirect.com\/boat-lovers\/tag\/protective-boat-cover\/","og_site_name":"Boat Lovers Direct","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.boatcoversdirect.com\/boat-lovers\/tag\/protective-boat-cover\/","url":"https:\/\/www.boatcoversdirect.com\/boat-lovers\/tag\/protective-boat-cover\/","name":"protective boat cover Archives - Boat Lovers Direct","isPartOf":{"@id":"https:\/\/www.boatcoversdirect.com\/boat-lovers\/#website"},"inLanguage":"en-US"},{"@type":"WebSite","@id":"https:\/\/www.boatcoversdirect.com\/boat-lovers\/#website","url":"https:\/\/www.boatcoversdirect.com\/boat-lovers\/","name":"Boat Lovers Direct","description":"The official blog of Boat Covers Direct","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.boatcoversdirect.com\/boat-lovers\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.boatcoversdirect.com\/boat-lovers\/wp-json\/wp\/v2\/tags\/526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.boatcoversdirect.com\/boat-lovers\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.boatcoversdirect.com\/boat-lovers\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.boatcoversdirect.com\/boat-lovers\/wp-json\/wp\/v2\/posts?tags=526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}